{"id":26930,"date":"2022-04-04T11:25:23","date_gmt":"2022-04-04T09:25:23","guid":{"rendered":"https:\/\/www.villagreta.pl\/reisefuehrer\/verleih-kajak-ponton-schlesien\/"},"modified":"2026-08-10T00:40:42","modified_gmt":"2026-08-09T22:40:42","slug":"verleih-kajak-ponton-schlesien","status":"publish","type":"post","link":"https:\/\/www.villagreta.pl\/de\/reisefuehrer\/activ\/verleih-kajak-ponton-schlesien\/","title":{"rendered":"Kajaks und Pontons in Niederschlesien"},"content":{"rendered":"<ul>\n<li>Es gibt mehrere Fl\u00fcsse in den Sudeten, die sich hervorragend zum Kajakfahren und Ponton-Rafting eignen<\/li>\n<li>Dazu geh\u00f6ren die Fl\u00fcsse B\u00f3br und Nysa K\u0142odzka<\/li>\n<li>Kanu-Biber beginnt im Dorf Nielestno. Es gibt mehrere Kajakverleihe und Pontonverleih <\/li>\n<li>Es gibt auch mehrere Stauseen, an denen Sie Segelboote oder Tretboote mieten k\u00f6nnen<\/li>\n<li>Wenn Sie &#8222;Wasser\u201d m\u00f6gen, schauen Sie <a href=\"https:\/\/www.villagreta.pl\/de\/reisefuehrer\/?filter_aktywnosc=woda\">hier<\/a> vorbei<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Kajak-, Ponton- und Tretbootverleih in Niederschlesien und den Sudeten.<\/p>\n","protected":false},"author":2,"featured_media":21507,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_titles_title":"Kajak- und Pontonverleih | B\u00f3br | Fluss Niederschlesien","_seopress_titles_desc":"Rafting auf dem Fluss B\u00f3br | Kajakverleih | Pontonverleih | Rafting auf der Biber-| | Preisliste Arbeitszeiten | Reservierung","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"none","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"beide","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"inline_featured_image":false,"footnotes":""},"categories":[158],"tags":[],"region":[198,195],"pogoda":[216],"najblizsze_miasto":[253,283,274],"aktywnosc":[306],"miejsca":[],"dzieci":[],"class_list":["post-26930","post","type-post","status-publish","format-standard","has-post-thumbnail","category-activ","region-katzbach-gebirge","region-isergebirge","pogoda-hitze","najblizsze_miasto-hirschberg","najblizsze_miasto-lahn","najblizsze_miasto-loewenberg","aktywnosc-wasser"],"acf":{"g_tel":"","g_tel_2":"","g_email":"","g_www":"","g_adres":"","g_route":"","g_vg_odleglosc":"","g_coords":{"lat":"","lng":""},"g_contact_extra_info":"","g_parking":"","g_mapa":null,"g_czas":"","g_dlugosc_trasy":"","g_przewyzszenie":"","g_faq":null},"_links":{"self":[{"href":"https:\/\/www.villagreta.pl\/de\/wp-json\/wp\/v2\/posts\/26930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.villagreta.pl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.villagreta.pl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.villagreta.pl\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.villagreta.pl\/de\/wp-json\/wp\/v2\/comments?post=26930"}],"version-history":[{"count":0,"href":"https:\/\/www.villagreta.pl\/de\/wp-json\/wp\/v2\/posts\/26930\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.villagreta.pl\/de\/wp-json\/wp\/v2\/media\/21507"}],"wp:attachment":[{"href":"https:\/\/www.villagreta.pl\/de\/wp-json\/wp\/v2\/media?parent=26930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.villagreta.pl\/de\/wp-json\/wp\/v2\/categories?post=26930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.villagreta.pl\/de\/wp-json\/wp\/v2\/tags?post=26930"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/www.villagreta.pl\/de\/wp-json\/wp\/v2\/region?post=26930"},{"taxonomy":"pogoda","embeddable":true,"href":"https:\/\/www.villagreta.pl\/de\/wp-json\/wp\/v2\/pogoda?post=26930"},{"taxonomy":"najblizsze_miasto","embeddable":true,"href":"https:\/\/www.villagreta.pl\/de\/wp-json\/wp\/v2\/najblizsze_miasto?post=26930"},{"taxonomy":"aktywnosc","embeddable":true,"href":"https:\/\/www.villagreta.pl\/de\/wp-json\/wp\/v2\/aktywnosc?post=26930"},{"taxonomy":"miejsca","embeddable":true,"href":"https:\/\/www.villagreta.pl\/de\/wp-json\/wp\/v2\/miejsca?post=26930"},{"taxonomy":"dzieci","embeddable":true,"href":"https:\/\/www.villagreta.pl\/de\/wp-json\/wp\/v2\/dzieci?post=26930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}